{"id":2686,"date":"2020-07-03T10:51:27","date_gmt":"2020-07-03T08:51:27","guid":{"rendered":"https:\/\/devb-borstbloembollen.smeder.nl\/veredeling-pioenenrassen\/"},"modified":"2024-06-11T10:31:24","modified_gmt":"2024-06-11T08:31:24","slug":"breeding","status":"publish","type":"page","link":"https:\/\/borstbloembollen.nl\/en\/peonies\/breeding\/","title":{"rendered":"Breeding"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":2103,"parent":2690,"menu_order":25,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2686","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Breeding - Peonies - Borst Bloembollen<\/title>\n<meta name=\"description\" content=\"Wij zetten graag nieuwe innovatieve pioenrassen in de markt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/borstbloembollen.nl\/en\/peonies\/breeding\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Breeding - Peonies - Borst Bloembollen\" \/>\n<meta property=\"og:description\" content=\"Wij zetten graag nieuwe innovatieve pioenrassen in de markt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/borstbloembollen.nl\/en\/peonies\/breeding\/\" \/>\n<meta property=\"og:site_name\" content=\"Borst Bloembollen\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-11T08:31:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/borstbloembollen.nl\/wp-content\/uploads\/2020\/08\/Borst19555-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1158\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/borstbloembollen.nl\\\/en\\\/peonies\\\/breeding\\\/\",\"url\":\"https:\\\/\\\/borstbloembollen.nl\\\/en\\\/peonies\\\/breeding\\\/\",\"name\":\"Breeding - Peonies - Borst Bloembollen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/borstbloembollen.nl\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/borstbloembollen.nl\\\/en\\\/peonies\\\/breeding\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/borstbloembollen.nl\\\/en\\\/peonies\\\/breeding\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/borstbloembollen.nl\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Borst19555-scaled.jpg\",\"datePublished\":\"2020-07-03T08:51:27+00:00\",\"dateModified\":\"2024-06-11T08:31:24+00:00\",\"description\":\"Wij zetten graag nieuwe innovatieve pioenrassen in de markt.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/borstbloembollen.nl\\\/en\\\/peonies\\\/breeding\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/borstbloembollen.nl\\\/en\\\/peonies\\\/breeding\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/borstbloembollen.nl\\\/en\\\/peonies\\\/breeding\\\/#primaryimage\",\"url\":\"https:\\\/\\\/borstbloembollen.nl\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Borst19555-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/borstbloembollen.nl\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Borst19555-scaled.jpg\",\"width\":2560,\"height\":1158},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/borstbloembollen.nl\\\/en\\\/peonies\\\/breeding\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/borstbloembollen.nl\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Peonies\",\"item\":\"https:\\\/\\\/borstbloembollen.nl\\\/en\\\/peonies\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Breeding\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/borstbloembollen.nl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/borstbloembollen.nl\\\/en\\\/\",\"name\":\"Borst Bloembollen\",\"description\":\"Gespecialiseerd in het vermeerderen en introduceren van de beste en nieuwste tulpen cultivars\",\"publisher\":{\"@id\":\"https:\\\/\\\/borstbloembollen.nl\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/borstbloembollen.nl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/borstbloembollen.nl\\\/en\\\/#organization\",\"name\":\"Borst Bloembollen\",\"url\":\"https:\\\/\\\/borstbloembollen.nl\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/borstbloembollen.nl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/borstbloembollen.nl\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/BorstBloembollen-1x1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/borstbloembollen.nl\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/BorstBloembollen-1x1-1.jpg\",\"width\":370,\"height\":370,\"caption\":\"Borst Bloembollen\"},\"image\":{\"@id\":\"https:\\\/\\\/borstbloembollen.nl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Breeding - Peonies - Borst Bloembollen","description":"Wij zetten graag nieuwe innovatieve pioenrassen in de markt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/borstbloembollen.nl\/en\/peonies\/breeding\/","og_locale":"en_US","og_type":"article","og_title":"Breeding - Peonies - Borst Bloembollen","og_description":"Wij zetten graag nieuwe innovatieve pioenrassen in de markt.","og_url":"https:\/\/borstbloembollen.nl\/en\/peonies\/breeding\/","og_site_name":"Borst Bloembollen","article_modified_time":"2024-06-11T08:31:24+00:00","og_image":[{"width":2560,"height":1158,"url":"https:\/\/borstbloembollen.nl\/wp-content\/uploads\/2020\/08\/Borst19555-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/borstbloembollen.nl\/en\/peonies\/breeding\/","url":"https:\/\/borstbloembollen.nl\/en\/peonies\/breeding\/","name":"Breeding - Peonies - Borst Bloembollen","isPartOf":{"@id":"https:\/\/borstbloembollen.nl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/borstbloembollen.nl\/en\/peonies\/breeding\/#primaryimage"},"image":{"@id":"https:\/\/borstbloembollen.nl\/en\/peonies\/breeding\/#primaryimage"},"thumbnailUrl":"https:\/\/borstbloembollen.nl\/wp-content\/uploads\/2020\/08\/Borst19555-scaled.jpg","datePublished":"2020-07-03T08:51:27+00:00","dateModified":"2024-06-11T08:31:24+00:00","description":"Wij zetten graag nieuwe innovatieve pioenrassen in de markt.","breadcrumb":{"@id":"https:\/\/borstbloembollen.nl\/en\/peonies\/breeding\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/borstbloembollen.nl\/en\/peonies\/breeding\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/borstbloembollen.nl\/en\/peonies\/breeding\/#primaryimage","url":"https:\/\/borstbloembollen.nl\/wp-content\/uploads\/2020\/08\/Borst19555-scaled.jpg","contentUrl":"https:\/\/borstbloembollen.nl\/wp-content\/uploads\/2020\/08\/Borst19555-scaled.jpg","width":2560,"height":1158},{"@type":"BreadcrumbList","@id":"https:\/\/borstbloembollen.nl\/en\/peonies\/breeding\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/borstbloembollen.nl\/en\/"},{"@type":"ListItem","position":2,"name":"Peonies","item":"https:\/\/borstbloembollen.nl\/en\/peonies\/"},{"@type":"ListItem","position":3,"name":"Breeding"}]},{"@type":"WebSite","@id":"https:\/\/borstbloembollen.nl\/en\/#website","url":"https:\/\/borstbloembollen.nl\/en\/","name":"Borst Bloembollen","description":"Gespecialiseerd in het vermeerderen en introduceren van de beste en nieuwste tulpen cultivars","publisher":{"@id":"https:\/\/borstbloembollen.nl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/borstbloembollen.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/borstbloembollen.nl\/en\/#organization","name":"Borst Bloembollen","url":"https:\/\/borstbloembollen.nl\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/borstbloembollen.nl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/borstbloembollen.nl\/wp-content\/uploads\/2020\/09\/BorstBloembollen-1x1-1.jpg","contentUrl":"https:\/\/borstbloembollen.nl\/wp-content\/uploads\/2020\/09\/BorstBloembollen-1x1-1.jpg","width":370,"height":370,"caption":"Borst Bloembollen"},"image":{"@id":"https:\/\/borstbloembollen.nl\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/borstbloembollen.nl\/en\/wp-json\/wp\/v2\/pages\/2686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borstbloembollen.nl\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/borstbloembollen.nl\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/borstbloembollen.nl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/borstbloembollen.nl\/en\/wp-json\/wp\/v2\/comments?post=2686"}],"version-history":[{"count":10,"href":"https:\/\/borstbloembollen.nl\/en\/wp-json\/wp\/v2\/pages\/2686\/revisions"}],"predecessor-version":[{"id":11013,"href":"https:\/\/borstbloembollen.nl\/en\/wp-json\/wp\/v2\/pages\/2686\/revisions\/11013"}],"up":[{"embeddable":true,"href":"https:\/\/borstbloembollen.nl\/en\/wp-json\/wp\/v2\/pages\/2690"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/borstbloembollen.nl\/en\/wp-json\/wp\/v2\/media\/2103"}],"wp:attachment":[{"href":"https:\/\/borstbloembollen.nl\/en\/wp-json\/wp\/v2\/media?parent=2686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}